{"id":48868,"date":"2022-03-05T09:00:44","date_gmt":"2022-03-05T08:00:44","guid":{"rendered":"https:\/\/www.wumingfoundation.com\/giap\/?p=48868"},"modified":"2022-03-05T12:34:30","modified_gmt":"2022-03-05T11:34:30","slug":"centenario-pasolini","status":"publish","type":"post","link":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/","title":{"rendered":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata"},"content":{"rendered":"<div id=\"attachment_48871\" style=\"width: 718px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48871\" class=\"wp-image-48871 size-full\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg\" alt=\"\" width=\"708\" height=\"483\" srcset=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg 708w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-300x205.jpg 300w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-368x251.jpg 368w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-200x136.jpg 200w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-702x479.jpg 702w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-586x400.jpg 586w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739-519x354.jpg 519w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><p id=\"caption-attachment-48871\" class=\"wp-caption-text\">\u00abL&#8217;Espresso\u00bb, 23 giugno 1974.<\/p><\/div>\n<p>[<strong>WM1<\/strong>:] Ciclicamente si torna sulla vita e le opere di <strong>Pier Paolo Pasolini<\/strong>. Moltissimo sulla vita (e sulla morte), meno sulle opere, molto citate ma poco lette o, nel caso dei film, viste.<\/p>\n<p>Stavolta si torna a Pasolini per via della ricorrenza tonda tonda che pi\u00f9 tonda non si potrebbe: oggi \u00e8 infatti il centenario della nascita, e da giorni siamo presi in un <em>agencement<\/em> di roba buona, scadente e pessima, tra convegni, mostre, documentari, podcast, monologhi teatrali, retrospettive cinematografiche, repliche televisive, riedizioni critiche e <em>acritiche<\/em>, coccodrilli impagliati nel &#8217;75, memi con virgolettati fuori contesto.<\/p>\n<p>Su tutto campeggia il <em>volto<\/em> di Pasolini, che gli zigomi forti fanno sempre sembrare scavato. La figura di Pasolini \u00e8 prima divenuta icona, poi santino, poi <em>significante qualsivoglia<\/em> a cui associare qualunque significato.<!--more--><\/p>\n<p>Dell&#8217;arbitrio con cui si tira in ballo Pasolini mi sono occupato molto nella seconda met\u00e0 degli anni Dieci. Ne ho scritto qui su <em>Giap<\/em> e sull&#8217;edizione online di <em>Internazionale<\/em>. L&#8217;articolo del 2015 in cui smontavo <a href=\"https:\/\/www.internazionale.it\/reportage\/wu-ming-1\/2015\/10\/29\/pasolini-polizia-anniversario-morte\">l&#8217;oscena menzogna su \u00abPasolini che stava con la polizia\u00bb<\/a> \u00e8 tuttora uno dei pi\u00f9 letti nella storia di quel sito, ed \u00e8 stato tradotto in molte lingue. Ho scritto molto anche di come un certo uso delle categorie di \u00abfascismo\u00bb e \u00abantifascismo\u00bb da parte di Pasolini sia alla radice di equivoci grossolani, di cui alcuni mestatori hanno approfittato per fabbricare veri e propri falsi (cfr. il paragrafo 3 di <a href=\"https:\/\/www.wumingfoundation.com\/giap\/2018\/07\/pieta-per-la-nazione\/\">quest&#8217;inchiesta<\/a>, intitolato \u00abChi ha fabbricato il meme del &#8220;caro Alberto&#8221;\u00bb).<\/p>\n<p>Il 18 maggio 2018 ho partecipato al convegno \u00abPasolini. All&#8217;origine del postmoderno\u00bb, organizzato a Forl\u00ec da <strong>Paolo Andreoni<\/strong>, <strong>Andrea Mandolesi<\/strong> e <strong>Michele Drudi<\/strong>. In quell&#8217;occasione ho tratto una sintesi da tutte le mie riflessioni su Pasolini, fascismo, neofascismo, consumismo ecc. Gli atti del convegno sono stati pubblicati l&#8217;anno dopo <a href=\"https:\/\/www.ibs.it\/pier-paolo-pasolini-all-origine-libro-vari\/e\/9788899322663\">per i tipi de L&#8217;Arcolaio<\/a>. Nel libro, il mio intervento si intitola <em>Pasolini e il neofascismo. Dalla merce come nuovo fascismo al neofascismo come merce: una quarantennale foresta di equivoci<\/em>. Il centenario mi sembra l&#8217;occasione giusta per <span style=\"color: #ff0000;\"><strong>\u2192<\/strong><\/span> <strong><a href=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/Wu_Ming_1_Pasolini_e_il_neofascismo.pdf\">renderlo disponibile in pdf<\/a><\/strong>.<\/p>\n<p>In molte sue parti, ritengo questo testo pi\u00f9 attuale di quando l&#8217;ho scritto. Ma \u00e8 diventato <em>pi\u00f9 attuale<\/em> non seguendo una traiettoria lineare, bens\u00ec obliquamente.<\/p>\n<p>All&#8217;osso, qui si parla di come un uso malaccorto del concetto di \u00abfascismo\u00bb, un uso che ne dia troppo per scontata la comprensione da parte di chi legge e ascolta, possa generare mostri.<\/p>\n<p>Il \u00abfascismo\u00bb usato come figura retorica \u2013 allegoria, metafora, metonimia, sineddoche \u2013 pu\u00f2 portare a malintesi che prima di ogni altra cosa limitano la comprensione del fenomeno a cui ci si sta riferendo. E pu\u00f2 succedere di peggio, come quando il facile ricorso all&#8217;epiteto \u00abfascista\u00bb sostituisce l&#8217;analisi con una sentenza sommaria preventiva, e basta non sottoscrivere subito tale condanna, basta chiedere un &#8220;supplemento d&#8217;indagine&#8221;, per essere additati come nemici, e come fascisti <em>by association<\/em>.<\/p>\n<p>Si pensi a un movimento di massa tanto inatteso ed enigmatico quanto <em>precursore<\/em> come i <strong>Gilets Jaunes<\/strong> che nel 2018-2019 hanno mobilitato milioni di persone in tutta la Francia e costretto <strong>Emmanuel Macron<\/strong> a una repressione poliziesca senza precedenti. In gran parte della &#8220;sinistra&#8221; italiana \u2013 \u00e8 una cosa molto cisalpina \u2013 l&#8217;opinione comune \u00e8 ancora che quello sia stato un movimento \u00abfascista\u00bb, e chi lo nega evidentemente ha simpatie per i fascisti. Ecco, non avendo capito nulla dei GJ, era <em>impossibile<\/em> che si comprendesse qualcosa di altre eruzioni sociali simili scoppiate nel 2020-2021.<\/p>\n<p>Pensiamo appunto ai due anni dell&#8217;emergenza pandemica, cio\u00e8 <a href=\"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/virus-militarismo\/\">del <em>militarismo<\/em> pandemico<\/a>, dell&#8217;intruppamento, della polarizzazione estrema gestita da politici e <em>influenzatori<\/em> a loro volta incentivati da algoritmi tecnologici che a loro volta sono il prodotto di algoritmi <em>sociali<\/em>, cio\u00e8 della logica dell&#8217;odierno capitalismo.<\/p>\n<div id=\"attachment_48873\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48873\" class=\"wp-image-48873\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/salo-ou-les-120-journees-de-sodome-pier-paolo-pasolini_4213026.jpg\" alt=\"\" width=\"700\" height=\"392\" srcset=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/salo-ou-les-120-journees-de-sodome-pier-paolo-pasolini_4213026.jpg 640w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/salo-ou-les-120-journees-de-sodome-pier-paolo-pasolini_4213026-300x168.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><p id=\"caption-attachment-48873\" class=\"wp-caption-text\">\u00abSal\u00f2\u00bb, 1975. Su questo film si vedano gli appunti del 2010 intitolati <a href=\"https:\/\/www.wumingfoundation.com\/giap\/2010\/04\/branco-75\/\"><em>Branco &#8217;75<\/em><\/a>.<\/p><\/div>\n<p>In questi due anni non \u00e8 stato forse accusato \u2013 ossessivamente, assurdamente, anche <em>carognescamente<\/em> accusato \u2013 di \u00abfascismo\u00bb, o quantomeno di \u00abstare coi fascisti\u00bb, chiunque \u2013 compresi noialtri Wu Ming \u2013 contestasse la pericolosa cornice retorica della \u00abguerra al virus\u00bb, denunciasse le ipocrisie e gli scaricabarile della gestione governativa, facesse notare l&#8217;irrazionalit\u00e0 di molti provvedimenti, si esprimesse sulle molte incongruit\u00e0 del lasciapassare verde?<\/p>\n<p>Apparentemente ci siamo allontanati da Pasolini. In realt\u00e0 no, perch\u00e9 questi sono proprio i &#8220;suoi&#8221; temi: l&#8217;ipocrisia criminale della classe dirigente; l&#8217;arroganza del <em>ratiosuprematismo <\/em>e di chi usa il sapere, la cultura e la scienza come randelli classisti; il ciclico cedimento della &#8220;sinistra&#8221; allo status quo descritto come &#8220;progressista&#8221;, e le fatali ambiguit\u00e0 della rivolta a un dominio che non viene percepito come tale ma si esercita tramite <em>una nuova semiotica dei corpi<\/em>, tramite una nuova <em>prossemica<\/em>.<\/p>\n<p>A partire da <em>Empirismo eretico<\/em>, Pasolini si sforza di spiegare &#8211; inventandosi anche parole, quando non ne trova che rendano l&#8217;idea \u2013 che le relazioni tra gli umani hanno preso a funzionare secondo nuovi algoritmi sociali, procedimenti sistematici di calcolo. Anche la lingua ne \u00e8 riplasmata. Nel \u00abneocapitalismo\u00bb si \u00e8 tutti apparentemente pi\u00f9 liberi ma in balia di pi\u00f9 numerosi e sinergici automatismi.<\/p>\n<p>In <em>Petrolio<\/em> Pasolini arriva vicinissimo a immaginare il \u00abmetaverso\u00bb, senza aver immaginato prima le tecnologie digitali e men che meno i social media. L&#8217;Italia neocapitalistica \u00e8 descritta come sdoppiata tra reale e virtuale, e diversi personaggi del romanzo \u2013 a cominciare dal protagonista Carlo \u2013 hanno qualcosa di simile a un <em>avatar<\/em>. Ma non \u00e8 questo post &#8220;di segnalazione&#8221; la sede in cui sviluppare tali spunti.<em><br \/>\n<\/em><\/p>\n<p><a href=\"https:\/\/www.archivioluce.com\/2022\/03\/04\/perche-pasolini\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-48872\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/copertina-PERCHE-PASOLINI-definitiva-300x300-1.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/copertina-PERCHE-PASOLINI-definitiva-300x300-1.jpg 300w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/copertina-PERCHE-PASOLINI-definitiva-300x300-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>L&#8217;approccio a Pasolini, ad ogni modo, non pu\u00f2 essere meramente apologetico, tutto santini e <em>ipse dixit<\/em>. Alcuni errori di impostazione del Pasolini saggista e &#8220;polemista&#8221; hanno avuto un effetto palla di neve. Certe tendenze che vedeva come di lungo corso si sono arrestate prima di quanto pensasse, altre che vedeva di corto respiro ancora corrono. \u00c8 quello che ho provato a dimostrare <a href=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/Wu_Ming_1_Pasolini_e_il_neofascismo.pdf\">nel testo ora scaricabile<\/a>.<\/p>\n<p>Colgo l&#8217;occasione per segnalare anche un mio breve, modestissimo contributo al podcast <a href=\"https:\/\/www.archivioluce.com\/2022\/03\/05\/perche-pasolini-tutte-le-puntate-del-podcast\/\"><em>Perch\u00e9 Pasolini?<\/em><\/a>, curato da <strong>Walter Siti <\/strong>e prodotto da Chora Media per l&#8217;Archivio Luce. Siti mi ha intervistato per strada, a Bologna, qualche tempo fa, e parte di ci\u00f2 che gli ho detto si pu\u00f2 ascoltare nella prima puntata, disponibile da oggi su varie piattaforme.<\/p>\n<p>_<\/p>\n<p><span style=\"font-size: small;\">Come spiegato <a href=\"https:\/\/www.wumingfoundation.com\/giap\/2022\/02\/a-che-punto-e-wu-ming-2022\/\">nell&#8217;ultimo aggiornamento complessivo<\/a>, in questa fase <em>Giap<\/em> funziona &#8220;col motore al minimo&#8221;. Soprattutto, mancano le energie per gestire lo spazio commenti. Ecco perch\u00e9 sotto i nuovi post mettiamo il &#8220;lucchetto&#8221;. Ce ne scusiamo, purtroppo va cos\u00ec.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"[WM1:] Ciclicamente si torna sulla vita e le opere di Pier Paolo Pasolini. Moltissimo sulla vita (e sulla morte), meno sulle opere, molto citate ma poco lette o, nel caso dei film, viste. Stavolta si torna a Pasolini per via della ricorrenza tonda tonda che pi\u00f9 tonda non si potrebbe: oggi \u00e8 infatti il centenario [&hellip;]","protected":false},"author":1,"featured_media":48871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,6],"tags":[97,4613,4614],"class_list":["post-48868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editoriali","category-news-e-segnalazioni","tag-pasolini","tag-perche-pasolini","tag-walter-siti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap<\/title>\n<meta name=\"description\" content=\"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap\" \/>\n<meta property=\"og:description\" content=\"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/\" \/>\n<meta property=\"og:site_name\" content=\"Giap\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-05T08:00:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-05T11:34:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"708\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wu Ming\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:site\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wu Ming\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/\"},\"author\":{\"name\":\"Wu Ming\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"headline\":\"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata\",\"datePublished\":\"2022-03-05T08:00:44+00:00\",\"dateModified\":\"2022-03-05T11:34:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/\"},\"wordCount\":1073,\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ppp-e1646416916739.jpg\",\"keywords\":[\"Pasolini\",\"Perch\u00e9 Pasolini?\",\"Walter Siti\"],\"articleSection\":[\"Esternazioni\",\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/\",\"name\":\"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ppp-e1646416916739.jpg\",\"datePublished\":\"2022-03-05T08:00:44+00:00\",\"dateModified\":\"2022-03-05T11:34:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"description\":\"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ppp-e1646416916739.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/ppp-e1646416916739.jpg\",\"width\":708,\"height\":483,\"caption\":\"\u00abL'Espresso\u00bb, 23 giugno 1974.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2022\\\/03\\\/centenario-pasolini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\",\"name\":\"Giap\",\"description\":\"Il sito ufficiale di Wu Ming, collettivo di scrittori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\",\"name\":\"Wu Ming\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"caption\":\"Wu Ming\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap","description":"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/","og_locale":"it_IT","og_type":"article","og_title":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap","og_description":"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.","og_url":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/","og_site_name":"Giap","article_published_time":"2022-03-05T08:00:44+00:00","article_modified_time":"2022-03-05T11:34:30+00:00","og_image":[{"width":708,"height":483,"url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg","type":"image\/jpeg"}],"author":"Wu Ming","twitter_card":"summary_large_image","twitter_creator":"@Wu_Ming_Foundt","twitter_site":"@Wu_Ming_Foundt","twitter_misc":{"Scritto da":"Wu Ming","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#article","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/"},"author":{"name":"Wu Ming","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"headline":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata","datePublished":"2022-03-05T08:00:44+00:00","dateModified":"2022-03-05T11:34:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/"},"wordCount":1073,"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg","keywords":["Pasolini","Perch\u00e9 Pasolini?","Walter Siti"],"articleSection":["Esternazioni","Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/","url":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/","name":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata &#8211; Giap","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#primaryimage"},"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg","datePublished":"2022-03-05T08:00:44+00:00","dateModified":"2022-03-05T11:34:30+00:00","author":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"description":"Da Empirismo eretico in poi, Pasolini si sforza di spiegare che le relazioni tra umani funzionano secondo nuovi algoritmi sociali.","breadcrumb":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#primaryimage","url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg","contentUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2022\/03\/ppp-e1646416916739.jpg","width":708,"height":483,"caption":"\u00abL'Espresso\u00bb, 23 giugno 1974."},{"@type":"BreadcrumbList","@id":"https:\/\/www.wumingfoundation.com\/giap\/2022\/03\/centenario-pasolini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wumingfoundation.com\/giap\/"},{"@type":"ListItem","position":2,"name":"Su Pasolini e il suo centenario: di fascismi, algoritmi del dominio ed equivoci di lunga durata"}]},{"@type":"WebSite","@id":"https:\/\/www.wumingfoundation.com\/giap\/#website","url":"https:\/\/www.wumingfoundation.com\/giap\/","name":"Giap","description":"Il sito ufficiale di Wu Ming, collettivo di scrittori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wumingfoundation.com\/giap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f","name":"Wu Ming","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","caption":"Wu Ming"}}]}},"_links":{"self":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/48868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/comments?post=48868"}],"version-history":[{"count":7,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/48868\/revisions"}],"predecessor-version":[{"id":48911,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/48868\/revisions\/48911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media\/48871"}],"wp:attachment":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media?parent=48868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/categories?post=48868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/tags?post=48868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}