{"id":46669,"date":"2021-05-11T10:00:47","date_gmt":"2021-05-11T08:00:47","guid":{"rendered":"https:\/\/www.wumingfoundation.com\/giap\/?p=46669"},"modified":"2021-05-13T11:11:23","modified_gmt":"2021-05-13T09:11:23","slug":"quaderni-di-arda-2","status":"publish","type":"post","link":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/","title":{"rendered":"Uno sputnik costruito in garage: I Quaderni di Arda #2"},"content":{"rendered":"<p><a href=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-46831\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg\" alt=\"\" width=\"350\" height=\"263\" srcset=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg 2016w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2-300x225.jpg 300w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2-1024x768.jpg 1024w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2-768x576.jpg 768w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>Uno sputnik costruito in garage\u2026 \u00e8 entrato in orbita. \u00c8 l&#8217;immagine pi\u00f9 adatta per definire questa rivista, che battezza il suo numero 2, quello del 2021.<\/p>\n<p>Per spiegare la metafora bisogna considerare alcuni elementi. Sia il #1 sia questo #2 de \u00abI Quaderni di Arda\u00bb contengono gli atti di convegni tenutisi all&#8217;Universit\u00e0 di Trento (rispettivamente nel 2017 e nel 2020), promossi dall&#8217;<strong>Associazione Italiana Studi Tolkieniani<\/strong>, con l&#8217;aggiunta di alcuni contributi extra. Tanto gli interventi dei relatori quanto quelli aggiunti <em>ex post<\/em> nascono da un <em>melting pot<\/em> di studiosi professionisti (la maggior parte italiani e alcuni stranieri) e studiosi dilettanti (alcuni membri del Gruppo di Studi dell&#8217;AIST altri no), cio\u00e8 dall&#8217;incontro tra studio accademico e passione \u201cda fan\u201d. Il risultato \u00e8 una grande variet\u00e0 d&#8217;approcci.<\/p>\n<p>Accanto a studi filologici, stilistici, storico-letterari, si trovano articoli sui punti di contatto tra Tolkien e la narrativa fantascientifica e horror, sulle traduzioni delle sue storie attraverso le arti grafiche e la musica, sugli sviluppi transmediali del racconto tolkieniano o sulle mappe come supporto fondamentale alla \u201csub-creazione\u201d di mondo. Si va dalla filologia germanica, alle recensioni di saggi e cataloghi, all&#8217;indagine sulla fan fiction, abbattendo qualunque barriera architettonica che possa porsi in mezzo, eccetto quella della seriet\u00e0 d&#8217;approccio.<!--more--><\/p>\n<div id=\"attachment_46672\" style=\"width: 210px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-46672\" class=\"wp-image-46672 size-full\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Jenkins-Henry2.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Jenkins-Henry2.jpg 200w, https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Jenkins-Henry2-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><p id=\"caption-attachment-46672\" class=\"wp-caption-text\">Henry Jenkins<\/p><\/div>\n<p>La linea editoriale di fondo \u00e8 una declinazione, adeguata al contesto, della stessa attitudine che gi\u00e0 ispira tutta l&#8217;attivit\u00e0 del<a href=\"http:\/\/www.jrrtolkien.it\">l&#8217;AIST<\/a>, improntata alla <em>cultura convergente<\/em> e alla <em>cultura partecipativa,<\/em> per come le ha teorizzate <a href=\"https:\/\/it.wikipedia.org\/wiki\/Henry_Jenkins\"><strong>Henry Jenkins<\/strong><\/a>. Concetti e pratiche che disarticolano la narrazione conservatrice e autoconsolatoria \u201ccultura alta vs cultura bassa\u201d, \u201ccritica vs fandom\u201d, \u201csnob vs pop\u201d, buona per alimentare la nevrosi dei cultori della materia (quale che sia).<\/p>\n<p>E tuttavia \u00e8 chiaro che rendere gli ambiti specialistici permeabili alla critica partecipata dei fan e valorizzare l&#8217;angolazione del fandom per l&#8217;indagine e la conoscenza della narrativa &#8211; vedi il laboratorio di analisi del testo tenuto da <strong>Wu Ming 4<\/strong> proprio all&#8217;Universit\u00e0 di Trento, che si risolve di fatto nel fare scrivere agli studenti racconti di fan fiction tolkieniana o a questa ispirati &#8211; non va scambiato per un azzeramento dei criteri d&#8217;indagine stessi. Proprio come fare \u00abpopular history\u00bb non pu\u00f2 significare <a href=\"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/i-due-maraun\/\">pretendere di fare storia senza adottare gli strumenti della ricerca storica<\/a>, allo stesso modo fare \u00abpopular criticism\u00bb non equivale a trasformare la passione per un oggetto narrativo in un principio d&#8217;autorit\u00e0 autosufficiente, uguale e contrario allo specialismo accademico. Il punto, se mai, \u00e8 uscire dalle reciproche zone di comfort e mettersi in gioco in campo aperto, affrontando le difficolt\u00e0 che questo comporta. Per parafrasare l&#8217;elfo Gildor Inglorion: chiudersi nelle proprie contee\/nicchie &#8211; siano quelle accademiche o quelle del fandom, ciascuna con i suoi gelosi <em>gatekeepers<\/em> &#8211; non cambia il fatto che tutt&#8217;intorno c&#8217;\u00e8 un mondo intero e che questo non pu\u00f2 essere lasciato fuori per sempre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46745 alignright\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Copertina01-217x300-1.jpg\" alt=\"\" width=\"200\" height=\"276\" \/>Questo #2 monografico dei \u00abQuaderni di Arda\u00bb \u00e8 anche una dimostrazione metodologica. Dopo due anni di polemiche intorno alla nuova traduzione del <em>Signore degli Anelli<\/em> (\u00abintorno\u00bb nel senso che l&#8217;hanno preceduta, accompagnata e seguita), la rivista inserisce il dibattito in un contesto ben pi\u00f9 ampio e complesso. Facendo parlare i traduttori italiani di Tolkien, due traduttrici straniere, filologi e studiosi di letteratura, e raffrontando le varie traduzioni e ritraduzioni in diverse lingue europee, si definisce un vero e proprio \u201ccaso di studio\u201d per chiunque sia interessato alla pratica e alla teoria della traduzione (anche a prescindere da Tolkien) e alla diversa ricezione di un&#8217;opera letteraria nei vari contesti linguistici.<\/p>\n<p>Nell&#8217;esperienza dei Quaderni di Arda, accademici, traduttori, giornalisti, critici letterari, studiosi dilettanti e semplici appassionati, sono coinvolti in un progetto che conta gi\u00e0 due numeri in versione online e cartacea (con alcune differenze mantenute tra l&#8217;una e l&#8217;altra nelle sezioni <em>Off<\/em> ed <em>Extra<\/em>), che rappresentano di per s\u00e9 due raccolte di saggi tra le pi\u00f9 originali ed eterogenee prodotte in contesto italiano sull&#8217;autore in questione.<\/p>\n<p>Se per l&#8217;organizzazione dei convegni a fare la parte del leone \u00e8 soprattutto l&#8217;<strong>Universit\u00e0 di Trento<\/strong> nel suo dipartimento di Lettere e Filosofia (bench\u00e9 gli accademici coinvolti facciano capo ad almeno sei atenei diversi), per quanto riguarda la rivista promossa dall&#8217;AIST si pu\u00f2 dire che \u00e8 realizzata davvero con pochi mezzi e zero finanziamenti. A fronte di un board che conta alcuni dei pi\u00f9 importanti studiosi tolkieniani al mondo, il collettivo redazionale \u00e8 attualmente composto da sei persone, tra redattori e redattrici, quasi tutte alla loro prima esperienza di questo tipo, alle quali si aggiungono un webmaster e un impaginatore per <strong>Eterea Edizioni<\/strong>, la piccola casa editrice che pubblica la rivista.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-46746 alignleft\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Tolk-1.jpg\" alt=\"\" width=\"200\" height=\"196\" \/>Rispetto alla rotta, infine, si pu\u00f2 dire che il viaggio parte da Tolkien, ma per andare oltre. Non per niente la sottotestata \u00e8: \u00abrivista di studi tolkieniani e mondi fantastici\u00bb. Si tratta di indagare la narrativa fantastica, di genere, e non solo, nelle sue varie forme, fino alle pi\u00f9 recenti, ovvero di tracciare mappe concettuali attraverso la letteratura e attraverso le epoche, usando Tolkien come <em>crocevia<\/em>. Crocevia di generi e di percorsi che partono dai poemi medievali, passando per il medievalismo ottocentesco inglese e il confronto con il modernismo del Novecento (o anche con il cosiddetto post-modernismo), per arrivare ai \u201cfigli e figliastri\u201d di Tolkien nel panorama narrativo attuale.<\/p>\n<p>Un numero monografico all&#8217;anno, senza fretta. Curato al meglio delle possibilit\u00e0. Testi liberamente accessibili <a href=\"http:\/\/www.iquadernidiarda.it\">on line<\/a>, <a href=\"https:\/\/etereaedizioni.com\/prodotto\/i-quaderni-di-arda-2\/\">elegante volume cartonato<\/a> per i supporter, i collezionisti e le biblioteche di dipartimento.<br \/>\nE che i Valar ce la mandino buona.<\/p>\n","protected":false},"excerpt":{"rendered":"Uno sputnik costruito in garage\u2026 \u00e8 entrato in orbita. \u00c8 l&#8217;immagine pi\u00f9 adatta per definire questa rivista, che battezza il suo numero 2, quello del 2021. Per spiegare la metafora bisogna considerare alcuni elementi. Sia il #1 sia questo #2 de \u00abI Quaderni di Arda\u00bb contengono gli atti di convegni tenutisi all&#8217;Universit\u00e0 di Trento (rispettivamente [&hellip;]","protected":false},"author":82,"featured_media":46831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[230,4092,1807],"class_list":["post-46669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-e-segnalazioni","tag-jrr-tolkien","tag-quaderni-di-arda","tag-traduzione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap<\/title>\n<meta name=\"description\" content=\"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap\" \/>\n<meta property=\"og:description\" content=\"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Giap\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T08:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-13T09:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wu Ming 4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:site\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wu Ming 4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/\"},\"author\":{\"name\":\"Wu Ming 4\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/fdd84c82f75aa2ffddcd90b279b6628c\"},\"headline\":\"Uno sputnik costruito in garage: I Quaderni di Arda #2\",\"datePublished\":\"2021-05-11T08:00:47+00:00\",\"dateModified\":\"2021-05-13T09:11:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/\"},\"wordCount\":917,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Quaderni-di-Arda-2.jpg\",\"keywords\":[\"JRR Tolkien\",\"Quaderni di Arda\",\"traduzione\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/\",\"name\":\"Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Quaderni-di-Arda-2.jpg\",\"datePublished\":\"2021-05-11T08:00:47+00:00\",\"dateModified\":\"2021-05-13T09:11:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/fdd84c82f75aa2ffddcd90b279b6628c\"},\"description\":\"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Quaderni-di-Arda-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Quaderni-di-Arda-2.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2021\\\/05\\\/quaderni-di-arda-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uno sputnik costruito in garage: I Quaderni di Arda #2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\",\"name\":\"Giap\",\"description\":\"Il sito ufficiale di Wu Ming, collettivo di scrittori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/fdd84c82f75aa2ffddcd90b279b6628c\",\"name\":\"Wu Ming 4\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g\",\"caption\":\"Wu Ming 4\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap","description":"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/","og_locale":"it_IT","og_type":"article","og_title":"Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap","og_description":"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.","og_url":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/","og_site_name":"Giap","article_published_time":"2021-05-11T08:00:47+00:00","article_modified_time":"2021-05-13T09:11:23+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg","type":"image\/jpeg"}],"author":"Wu Ming 4","twitter_card":"summary_large_image","twitter_creator":"@Wu_Ming_Foundt","twitter_site":"@Wu_Ming_Foundt","twitter_misc":{"Scritto da":"Wu Ming 4","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#article","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/"},"author":{"name":"Wu Ming 4","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/fdd84c82f75aa2ffddcd90b279b6628c"},"headline":"Uno sputnik costruito in garage: I Quaderni di Arda #2","datePublished":"2021-05-11T08:00:47+00:00","dateModified":"2021-05-13T09:11:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/"},"wordCount":917,"commentCount":0,"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg","keywords":["JRR Tolkien","Quaderni di Arda","traduzione"],"articleSection":["Notizie"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/","url":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/","name":"Uno sputnik costruito in garage: I Quaderni di Arda #2 &#8211; Giap","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#primaryimage"},"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg","datePublished":"2021-05-11T08:00:47+00:00","dateModified":"2021-05-13T09:11:23+00:00","author":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/fdd84c82f75aa2ffddcd90b279b6628c"},"description":"Nei Quaderni di Arda 2, Tolkien e la traduzione, Tolkien e le arti grafiche, Tolkien e la musica, Tolkien e la fantascienza ecc.","breadcrumb":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#primaryimage","url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg","contentUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2021\/05\/Quaderni-di-Arda-2.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.wumingfoundation.com\/giap\/2021\/05\/quaderni-di-arda-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wumingfoundation.com\/giap\/"},{"@type":"ListItem","position":2,"name":"Uno sputnik costruito in garage: I Quaderni di Arda #2"}]},{"@type":"WebSite","@id":"https:\/\/www.wumingfoundation.com\/giap\/#website","url":"https:\/\/www.wumingfoundation.com\/giap\/","name":"Giap","description":"Il sito ufficiale di Wu Ming, collettivo di scrittori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wumingfoundation.com\/giap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/fdd84c82f75aa2ffddcd90b279b6628c","name":"Wu Ming 4","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/649efaf3f0f1574b9e09524d996b8a5a0b11a72d6f990d63dc6023563a149d0e?s=96&d=blank&r=g","caption":"Wu Ming 4"}}]}},"_links":{"self":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/46669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/comments?post=46669"}],"version-history":[{"count":0,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/46669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media\/46831"}],"wp:attachment":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media?parent=46669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/categories?post=46669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/tags?post=46669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}