{"id":45598,"date":"2020-11-02T09:00:43","date_gmt":"2020-11-02T08:00:43","guid":{"rendered":"https:\/\/www.wumingfoundation.com\/giap\/?p=45598"},"modified":"2020-11-02T12:59:32","modified_gmt":"2020-11-02T11:59:32","slug":"spazio-vuoto-qanon","status":"publish","type":"post","link":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/","title":{"rendered":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: small;\"><a href=\"https:\/\/www.wumingfoundation.com\/giap\/blank-space-qanon\/\"><strong>English version here.<\/strong><\/a><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-45614\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png\" alt=\"\" width=\"350\" height=\"246\" \/><\/p>\n<p>di <strong>Florian Cramer<\/strong> e <strong>Wu Ming 1<\/strong><\/p>\n<p><em>QAnon &#8211; il movimento secondo cui Donald Trump combatte una guerra segreta contro \u00e9lites sataniste e pedofile \u2013 non \u00e8 la solita credenza complottistica, ma funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 anche il motivo della sua spropositata diffusione, che ora abbraccia i soggetti pi\u00f9 diversi, dai <\/em>Reichsb\u00fcrger<em> tedeschi [convinti che il Reich esista ancora e che la Repubblica Federale di Germania sia una compagnia senza basi legali registrata a Francoforte] a chi nega che sia in corso una pandemia. <\/em><em>Il fatto che la premessa narrativa di QAnon derivi da un assemblaggio di fonti letterarie e della cultura pop \u2013 tra le quali un romanzo del 1999 scritto anche da uno dei due autori di quest&#8217;articolo \u2013 non suscita dubbi nei seguaci.<br \/>\n<\/em><!--more--><\/p>\n<p>&#8220;QAnon&#8221; \u00e8 iniziato nell&#8217;autunno 2017 con una serie di messaggi frammentari da parte di un utente &#8220;Q&#8221; sul forum 4chan, uno dei pochi luoghi della rete ancora &#8220;sregolati&#8221;, dove negli anni Zero nacque il movimento mascherato &#8220;Anonymous&#8221;. Dal 2014, quando su 4chan si form\u00f2 un&#8217;orda di odiatori contro un&#8217;autrice di videogame femminista [il cosiddetto Gamergate], il forum scivol\u00f2 nel sessismo militante, nel razzismo e nell&#8217;antisemitismo. 4chan divenne uno dei quartieri generali dell&#8217;estrema destra &#8220;alternativa&#8221; (Alt-Right). Nel 2016, nella fase finale della campagna elettorale di Trump, l&#8217;Alt-Right diffuse la fantasticheria di complotto &#8220;Pizzagate&#8221;, secondo cui alti dirigenti del Partito Democratico tenevano bambini rinchiusi nel seminterrato di una pizzeria di Washington, per usarli come schiavi sessuali. Un sostenitore di quella teoria fece irruzione nel locale con un fucile, per scoprire che non c&#8217;era nessun seminterrato.<\/p>\n<p>La storia fin\u00ec solo in apparenza. Un anno pi\u00f9 tardi, la credenza in un complotto mondiale pedofilo da parte delle \u00e9lites liberal \u2013 complotto di cui facevano parte anche Hillary Clinton e George Soros \u2013 ebbe un revival nei messaggi criptici su 4chan del presunto agente segreto &#8220;Q&#8221;. La sua narrazione &#8211; che Trump stia portando avanti in segreto un&#8217;apocalittica battaglia finale contro una casta planetaria di pedofili satanisti che bevono sangue di bambini per mantenersi giovani \u2013 recupera leggende antisemite che circolavano gi\u00e0 nel Medioevo. Nelle sue interviste coi media, Trump incoraggia questa credenza rifiutandosi di prenderne le distanze. Almeno 25 candidati repubblicani al Congresso sono legati alla sottocultura QAnon. I gruppi Facebook dedicati a QAnon sono arrivati ad avere pi\u00f9 di tre milioni di iscritti. Nel corso del tentato assalto al Reichstag durante le proteste dei <em>Querdenker<\/em> [Pensatori Laterali] che negano l&#8217;esistenza del coronavirus, sventolava una grande bandiera di QAnon.<\/p>\n<div id=\"attachment_45615\" style=\"width: 281px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-45615\" class=\"size-full wp-image-45615\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/naidoo.jpg\" alt=\"Xavier Naidoo\" width=\"271\" height=\"186\" \/><p id=\"caption-attachment-45615\" class=\"wp-caption-text\">Xavier Naidoo<\/p><\/div>\n<p>In Germania e nei Paesi Bassi, QAnon si \u00e8 diffuso molto rapidamente negli ambienti dell&#8217;estrema destra esoterica che oggi nega sia in corso una pandemia. Le storie sui potenti che adorano il diavolo e bevono il sangue sono diffuse anche da celebri influencers come il cantante pop <strong>Xavier Naidoo<\/strong>. In Italia, la fantasticheria QAnon ha trasformato in negatori del virus persone disperate e rovinate economicamente, fornendo risposte assurde a legittimi dubbi su come il governo gestisce quest&#8217;emergenza.<\/p>\n<p>La mappatura del complotto mondiale sviluppata nell&#8217;ambito QAnon include &#8211; accanto a Trump, Clinton and Soros &#8211; tutti gli altri &#8220;soliti sospetti&#8221;, come gli Illuminati, JFK e Nostradamus. QAnon \u00e8 diventato una super-fantasticheria di complotto che cerca di integrare tutte le fantasticherie precedenti nella costruzione di un mondo alternativo e di una teologia politica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-45605\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/lot49.jpg\" alt=\"\" width=\"200\" height=\"323\" \/>Chi si \u00e8 formato nelle sottoculture e controculture del periodo che va dagli anni Sessanta agli anni Novanta trover\u00e0 tale cartografia familiare. Include alcuni degli stessi attori e fa gli stessi riferimenti incrociati onnicomprensivi che troviamo, ad esempio, nella trilogia di romanzi <em>Illuminatus!<\/em> di <strong>Robert Shea<\/strong> e <strong>Robert Anton Wilson <\/strong>(1975). <em>Illuminatus!<\/em>, a sua volta, cita <em>L&#8217;Incanto del Lotto 49<\/em> di <strong>Thomas Pynchon<\/strong> (1967), la cui eroina segue le tracce di una rete postale segreta e a quanto pare onnipresente chiamata &#8220;Tristero&#8221;, che di fatto \u00e8 una realt\u00e0 alternativa della controcultura americana. L&#8217;esistenza di Tristero, per\u00f2, rimane incerta fino alla fine del romanzo, e il suo mondo parallelo non \u00e8 una terra promessa, dato che ne fanno parte anche gruppi di estrema destra. In <em>Illuminatus!<\/em>, invece, Wilson e Shea giocano coi miti del complotto in modi pi\u00f9 svagati e pop.<\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45604 alignleft\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/Illuminatus_1.jpg\" alt=\"\" width=\"200\" height=\"280\" \/>Illuminatus!<\/em> divenne una lettura di culto, soprattutto tra gli hacker. Poich\u00e9 gli hacker, in senso lato, si occupano di sistemi e interconnessioni tra sistemi, storicamente la loro sottocultura ha familiarit\u00e0 sia con fondate ipotesi di complotto sia con l&#8217;immaginazione cospirativa. \u00c8 dunque probabile che la persona o il gruppo di persone che, dietro lo pseudonimo &#8220;Q&#8221;, ha alimentato questa fantasticheria coi suoi frammenti testuali provenga \u2013 come lo stesso 4chan \u2013 dall&#8217;orbita larga di tale sottocultura.<\/p>\n<p>Da quando si \u00e8 formata l&#8217;Alt-Right, 4chan e i suoi pi\u00f9 recenti corrispettivi 8chan\/8kun non sono pi\u00f9 frequentati solo da aggressivi smanettoni che passano il tempo facendo &#8220;shit-posting&#8221;: i loro memi politici arrivano nei social network mainstream, dove incontrano la credulit\u00e0 di persone che hanno affinit\u00e0 col revivalismo evangelico negli USA, e con le scene dell&#8217;estrema destra esoterica in Europa. I testi di QAnon sono letteralmente prosecuzioni del fondamentalismo cristiano: promettono, con la stessa espressione dei movimenti revivalisti del XVIII secolo, un &#8220;Grande Risveglio&#8221; e un&#8217;imminente battaglia finale del Bene contro il Male.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-45606\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/Qedizionespeciale.jpg\" alt=\"\" width=\"200\" height=\"319\" \/>Almeno una fonte di QAnon \u00e8 molto plausibile: il romanzo italiano <em>Q<\/em>, pubblicato nel 1999 e scritto anche da uno dei due autori del presente articolo, all&#8217;epoca membro del collettivo Luther Blissett. Q \u00e8 stato tradotto anche in tedesco e in inglese ed \u00e8 stato pubblicato in pi\u00f9 di trenta paesi. Il romanzo si svolge nel periodo della Riforma e racconta la storia di un agente segreto che, sotto il nome di &#8220;Q&#8221;, diffonde disinformazione e \u2013 proprio come il Q di &#8220;QAnon&#8221; &#8211; sostiene di avere accesso ad alte sfere del potere politico e a informazioni segrete. Nel libro, le lettere di Q convincono i contadini insorti guidati da Thomas M\u00fcntzer a combattere una battaglia in Turingia per farla finita per sempre con nobili e vescovi. Ma la battaglia si rivela una trappola mortale. Il &#8220;Q&#8221; di QAnon copia anche questo, quando dichiara imminente la &#8220;tempesta&#8221; della battaglia finale,\u00a0 quella in cui Trump liberer\u00e0 gli USA dal &#8220;Deep State&#8221; e dalle \u00e9lites liberal.<\/p>\n<p>I parallelismi tra il Q di Luther Blissett e quello di QAnon avevano gi\u00e0 attirato la nostra attenzione nel 2018. Media americani ne avevano parlato. Ovviamente, ci\u00f2 non ha scosso la fede in QAnon.<\/p>\n<p>Il modo in cui Q di Luther Blissett \u00e8 stato usato per QAnon ricorda la storia di un altro falso: gli antisemiti <em>Protocolli dei Savi Anziani di Sion<\/em>, che apparvero nel 1903 e documentavano una presunta cospirazione mondiale ebraica. In realt\u00e0 erano un montaggio e una riscrittura di altri testi, compreso un romanzo satirico anti-monarchico dell&#8217;ex-comunardo parigino <strong>Maurice Joly<\/strong>, pubblicato nel 1886.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-45607\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/pendolo.jpg\" alt=\"\" width=\"200\" height=\"289\" \/>L&#8217;episodio \u00e8 citato anche nel romanzo di <strong>Umberto Eco <\/strong><em>Il pendolo di Foucault<\/em> (1988), dove si ricorda che la fascista e antisemita inglese <strong>Nesta Webster<\/strong> interpret\u00f2 le somiglianze testuali tra i <em>Protocolli<\/em> e il romanzo di Joly come prove che Joly era parte del complotto. Probabilmente i credenti in QAnon interpreterebbero <em>Q<\/em> di Luther Blissett allo stesso modo. Il pendolo di <em>Foucault<\/em>, <em>come L&#8217;incanto del lotto 49<\/em> e <em>Illuminatus!<\/em>, \u00e8 un compendio letterario di fantasticherie di complotto, ed \u00e8 quello col pi\u00f9 chiaro intento istruttivo. Racconta di tre uomini che, per capriccio, costruiscono una fantasticheria di complotto ricombinando informazioni e leggende su societ\u00e0 segrete e movimenti occultisti, ma diventano sempre pi\u00f9 prigionieri del proprio gioco e finiscono per attirare l&#8217;attenzione di veri cospiratori politici.\u00a0 Il documento segreto che tentano di decifrare \u2013 e la cui natura frammentaria anticipa i messaggi di QAnon su 4chan \u2013 si rivela una banale lista della spesa.<\/p>\n<div id=\"attachment_45623\" style=\"width: 210px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-45623\" class=\"wp-image-45623\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/ISER.jpg\" alt=\"\" width=\"200\" height=\"143\" \/><p id=\"caption-attachment-45623\" class=\"wp-caption-text\">Wolfgang Iser<\/p><\/div>\n<p>Un anno prima dell&#8217;uscita del romanzo Eco, semiologo di professione, tenne una conferenza all&#8217;Universit\u00e0 di Costanza sulla \u00abdisputa delle interpretazioni\u00bb. In quella circostanza, defin\u00ec \u00absemiosi ermetica\u00bb \u2013 nell&#8217;accezione occultista del termine \u2013 l&#8217;idea secondo cui i testi si possano \u00abinterpretare all&#8217;infinito\u00bb. <em>Il pendolo di Foucault <\/em>racconta la semiosi ermetica in forma di romanzo<em>. <\/em>Eco tenne quella conferenza nella facolt\u00e0 dove negli anni Settanta era nata la &#8220;teoria della ricezione&#8221;. Uno dei suoi concetti-chiave, introdotto da <strong>Wolfgang Iser<\/strong>, \u00e8 quello degli spazi vuoti o <em>blanks <\/em>(in tedesco <em>Leerstellen<\/em>) nei testi letterari; costitutive rotture o mancanze di informazioni\u00a0 cui i lettori devono\u00a0 sopperire, per mezzo delle quali il significato pu\u00f2 emergere solo in un dialogo tra testo e lettore.<\/p>\n<p>I frammenti testuali di QAnon spingono all&#8217;estremo sia la semiosi ermetica sia il principio dello spazio vuoto e, semplificando, portano la teoria della ricezione nella cultura <em>popular<\/em>. Il mantra del movimento QAnon e dei Querdenker tedeschi \u00e8: le nostre non sono asserzioni definitive, ma provocazioni per il pensiero critico, su cui chiunque deve fare le proprie ricerche. Poich\u00e9 le &#8220;ricerche&#8221; dei seguaci di QAnon consistono in perlustrazioni delle proprie bolle tramite Google e YouTube, finiscono sempre per confermare le loro assunzioni di partenza e la loro visione del mondo mito-cospirativa, ma con la sensazione di aver raggiunto le proprie conclusioni attraverso un proprio lavoro di ricerca.<\/p>\n<p>QAnon \u00e8 un coinvolgente gioco interattivo. Questo ne spiega l&#8217;attrattivit\u00e0. Di fatto, QAnon \u00e8 un &#8220;Alternate Reality Game&#8221; (ARG). Gli ARG sono un genere che coniuga gioco on line e avventura di gruppo, per il quale fin dagli anni Novanta esiste un&#8217;industria ludica specializzata. Un ARG contiene indizi e misteri che i giocatori risolvono trovando informazioni fuori dal gioco e condividendole coi loro pari. Spesso gli ARG non hanno un finale gi\u00e0 scritto. E come suggerisce il loro nome, i loro intrecci costuiscono realt\u00e0 alternative che si estendono alle vite quotidiane dei giocatori e, in un certo senso, le infondono di magia.<\/p>\n<p><a href=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/paul_is_dead.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45616 alignleft\" src=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/paul_is_dead.jpg\" alt=\"\" width=\"200\" height=\"150\" \/><\/a>Un esempio di fantasticheria di complotto che funzionava gi\u00e0 come un alternate reality game \u00e8 &#8220;Paul is dead&#8221; \u2013 la credenza, a partire dal 1969, che il membro dei Beatles <strong>Paul McCartney<\/strong> fosse morto in un incidente d&#8217;auto tre anni prima e fosse stato rimpiazzato da un sosia. Una vasta sottocultura di fan americani dei Beatles \u2013 soprannominati &#8220;Cluesters&#8221;, cercatori di indizi \u2013 si form\u00f2 intorno a quella fantasia e cominci\u00f2 a condividere informazioni attraverso programmi radio, giornali locali, fanzine e passaparola. Nei versi delle canzoni, sulle copertine dei dischi e nel materiale promozionale trovavano e decifravano presunti messaggi segreti sulla morte di McCartney. Era un ARG ante litteram, per giunta decentrato e autorganizzato. Quella sottocultura esiste ancora e a partire dal 2000, grazie a Internet, ha anche vissuto una rinascita.<\/p>\n<p>Molti degli elementi costitutivi di QAnon erano gi\u00e0 presenti: la &#8220;ricerca&#8221;, la sovrainterpretazione paranoica dei prodotti della cultura pop per esporre un&#8217;orribile verit\u00e0, l&#8217;ossessione per la morte e il &#8220;doppio&#8221;. Oggi i seguaci di QAnon diffondono la voce che Barack Obama, Michelle Obama e Hillary Clinton sono stati arrestati, giustiziati a Guantanamo e sostituiti da cloni.<\/p>\n<p>Di recente, giornalisti e studiosi americani hanno descritto QAnon come una religione in formazione. Famiglie e coppie vivono esperienze drammatiche quando un loro componente scivola in quel mondo parallelo. Anche se Trump dovesse perdere le elezioni, quella credenza e quelle fantasie non svaniranno. La fine della sua presidenza, probabilmente, ne alimenterebbe lo status leggendario di messia, trasformandolo in un martire, una vittima del &#8220;Deep State&#8221; e dell&#8217;establishment liberal. Con un Trump rieletto, d&#8217;altronde, QAnon si ritroverebbe a dover spiegare come mai la salvezza non sia ancora arrivata. In ogni caso, gi\u00e0 ora QAnon sta conoscendo varie metamorfosi, che potrebbero accelerare e avere come esito una versione pi\u00f9 mainstream della fantasticheria di complotto.<\/p>\n<p><strong>Florian Cramer<\/strong> \u00e8 professore di cultura visiva alla Willem de Kooning Academy di Rotterdam.<\/p>\n<p><strong>Wu Ming 1<\/strong> \u00e8 membro del collettivo di scrittori e attivisti culturali Wu Ming, che fa base a Bologna. Il suo nuovo libro <em>La Q di Qomplotto<\/em> uscir\u00e0 nel gennaio 2021.<\/p>\n<p>Una versione ridotta di quest&#8217;articolo \u00e8 uscita in tedesco sulla <em>S\u00fcddeutsche Zeitung<\/em> del 30\/10\/2020.<\/p>\n","protected":false},"excerpt":{"rendered":"English version here. di Florian Cramer e Wu Ming 1 QAnon &#8211; il movimento secondo cui Donald Trump combatte una guerra segreta contro \u00e9lites sataniste e pedofile \u2013 non \u00e8 la solita credenza complottistica, ma funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 anche il motivo della sua spropositata diffusione, che ora abbraccia [&hellip;]","protected":false},"author":66,"featured_media":45614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1943],"tags":[4357,3745,3735,4359,308,4360,35,3699,4358,481],"class_list":["post-45598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inchieste","tag-florian-cramer","tag-il-pendolo-di-foucault","tag-illuminatus","tag-lincanto-del-lotto-49","tag-luther-blissett","tag-paul-is-dead","tag-q","tag-qanon","tag-thomas-pynchon","tag-umberto-eco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap<\/title>\n<meta name=\"description\" content=\"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap\" \/>\n<meta property=\"og:description\" content=\"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/\" \/>\n<meta property=\"og:site_name\" content=\"Giap\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T08:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-02T11:59:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"246\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Wu Ming 1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:site\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wu Ming 1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/\"},\"author\":{\"name\":\"Wu Ming 1\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/12c5d368d0cddd4e8c8d72e03b518547\"},\"headline\":\"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale\",\"datePublished\":\"2020-11-02T08:00:43+00:00\",\"dateModified\":\"2020-11-02T11:59:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/\"},\"wordCount\":1971,\"commentCount\":26,\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/qtrump.png\",\"keywords\":[\"Florian Cramer\",\"Il pendolo di Foucault\",\"Illuminatus\",\"L'incanto del lotto 49\",\"Luther Blissett\",\"Paul Is Dead\",\"Q\",\"QAnon\",\"Thomas Pynchon\",\"Umberto Eco\"],\"articleSection\":[\"Inchieste\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/\",\"name\":\"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/qtrump.png\",\"datePublished\":\"2020-11-02T08:00:43+00:00\",\"dateModified\":\"2020-11-02T11:59:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/12c5d368d0cddd4e8c8d72e03b518547\"},\"description\":\"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/qtrump.png\",\"contentUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/qtrump.png\",\"width\":350,\"height\":246},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2020\\\/11\\\/spazio-vuoto-qanon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\",\"name\":\"Giap\",\"description\":\"Il sito ufficiale di Wu Ming, collettivo di scrittori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/12c5d368d0cddd4e8c8d72e03b518547\",\"name\":\"Wu Ming 1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g\",\"caption\":\"Wu Ming 1\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap","description":"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/","og_locale":"it_IT","og_type":"article","og_title":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap","og_description":"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.","og_url":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/","og_site_name":"Giap","article_published_time":"2020-11-02T08:00:43+00:00","article_modified_time":"2020-11-02T11:59:32+00:00","og_image":[{"width":350,"height":246,"url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png","type":"image\/png"}],"author":"Wu Ming 1","twitter_card":"summary_large_image","twitter_creator":"@Wu_Ming_Foundt","twitter_site":"@Wu_Ming_Foundt","twitter_misc":{"Scritto da":"Wu Ming 1","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#article","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/"},"author":{"name":"Wu Ming 1","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/12c5d368d0cddd4e8c8d72e03b518547"},"headline":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale","datePublished":"2020-11-02T08:00:43+00:00","dateModified":"2020-11-02T11:59:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/"},"wordCount":1971,"commentCount":26,"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png","keywords":["Florian Cramer","Il pendolo di Foucault","Illuminatus","L'incanto del lotto 49","Luther Blissett","Paul Is Dead","Q","QAnon","Thomas Pynchon","Umberto Eco"],"articleSection":["Inchieste"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/","url":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/","name":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale &#8211; Giap","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#primaryimage"},"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png","datePublished":"2020-11-02T08:00:43+00:00","dateModified":"2020-11-02T11:59:32+00:00","author":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/12c5d368d0cddd4e8c8d72e03b518547"},"description":"QAnon funziona come un gioco collettivo di interpretazione testuale. Questo \u00e8 uno dei segreti del suo successo.","breadcrumb":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#primaryimage","url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png","contentUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2020\/10\/qtrump.png","width":350,"height":246},{"@type":"BreadcrumbList","@id":"https:\/\/www.wumingfoundation.com\/giap\/2020\/11\/spazio-vuoto-qanon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wumingfoundation.com\/giap\/"},{"@type":"ListItem","position":2,"name":"Blank Space QAnon. Sul successo di una fantasia di complotto come gioco collettivo di interpretazione testuale"}]},{"@type":"WebSite","@id":"https:\/\/www.wumingfoundation.com\/giap\/#website","url":"https:\/\/www.wumingfoundation.com\/giap\/","name":"Giap","description":"Il sito ufficiale di Wu Ming, collettivo di scrittori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wumingfoundation.com\/giap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/12c5d368d0cddd4e8c8d72e03b518547","name":"Wu Ming 1","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d27f34fe20acdd1e8774d83e7c55edd635e7a36382223f8302d6220b655355b0?s=96&d=blank&r=g","caption":"Wu Ming 1"}}]}},"_links":{"self":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/45598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/comments?post=45598"}],"version-history":[{"count":0,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/45598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media\/45614"}],"wp:attachment":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media?parent=45598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/categories?post=45598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/tags?post=45598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}