{"id":4550,"date":"2011-06-22T21:54:24","date_gmt":"2011-06-22T19:54:24","guid":{"rendered":"http:\/\/www.wumingfoundation.com\/giap\/?p=4550"},"modified":"2011-06-22T22:03:36","modified_gmt":"2011-06-22T20:03:36","slug":"trasparenza-il-venduto-dei-nostri-libri-al-31052011","status":"publish","type":"post","link":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/","title":{"rendered":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4560\" title=\"Non siamo noi quattro, almeno crediamo...\" src=\"http:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg\" alt=\"\" width=\"500\" height=\"380\" \/><\/p>\n<p>Come ogni anno, ecco l&#8217;Operazione Glasnost.<br \/>\n[Per i pi\u00f9 giovani: <em>glasnost<\/em> significa &#8220;trasparenza&#8221; in russo, era una parola molto in voga ai tempi di <a href=\"http:\/\/it.wikipedia.org\/wiki\/Michail_Gorba%C4%8D%C3%ABv\">Gorbaciov<\/a>. ]<!--more--><br \/>\nI motivi per cui rendiamo pubblici i dati di vendita dei nostri libri li abbiamo spiegati pi\u00f9 volte.\u00a0 <a href=\"http:\/\/www.wumingfoundation.com\/italiano\/glasnost2006.htm\">Nel 2006<\/a> scrivemmo:<\/p>\n<blockquote><p>\u00ab\u00a0Quando parliamo di copie &#8220;vendute&#8221;, c&#8217;\u00e8 ancora chi trova la cosa &#8220;inelegante&#8221;, sconveniente, venale, poco artistica. Dopo una presentazione di <em>New Thing<\/em> a Udine, un blogger si disse  indignato per il fatto che Wu Ming 1 avesse usato la parola &#8220;vendite&#8221;,  ed \u00e8 solo un esempio tra i tanti. Non ci si rende conto che quelle  vendite sono lettori, sono esseri umani in carne ed ossa che desiderano  leggere quel che scrive uno scrittore al punto da recarsi in libreria e  rinunciare a una parte del loro reddito pur di portarsi a casa le sue  parole. <em>Queste persone compiono un piccolo sacrificio per noi, il  minimo che possiamo fare \u00e8 non parlare dei soldi che hanno speso come se  ci facessero schifo.<\/em> [&#8230;] Incitiamo tutti i colleghi a  rendere noto quanto vendono: per trasparenza, per condividere  informazioni utili coi lettori, per dare un&#8217;idea di quanto si legga oggi  in Italia, di quale sia la soglia oltre la quale un libro \u00e8 considerato  &#8220;di successo&#8221; etc&#8230;\u00bb<\/p><\/blockquote>\n<p><strong>Nota\u00a0tecnica.<\/strong> Nel corso degli anni, per ottenere i dati del venduto siamo ricorsi a diverse procedure. All&#8217;inizio li ricavavamo dai nostri rendiconti annuali, cio\u00e8 dalla documentazione che accompagna il pagamento delle royalties, poi abbiamo scoperto che alcuni di quei numeri erano &#8220;proiezioni&#8221;, stime di vendita. Proviamo a spiegarci:<br \/>\n1) le royalties vengono pagate ogni anno solare (che \u00e8 anche l&#8217;anno fiscale), in base alle vendite dall&#8217;1 gennaio al 31 dicembre, per\u00f2&#8230;<br \/>\n2) &#8230;se un libro esce in autunno (es.\u00a0<em>New Thing<\/em>), al 31 dicembre non ci sono ancora state le rese ed \u00e8 impossibile sapere con certezza quanto abbia venduto. E allora&#8230;<br \/>\n3) &#8230;di solito si fa una stima di vendita in base alla &#8220;movimentazione&#8221; delle copie nei due-tre mesi di presenza in libreria, e si paga l&#8217;autore in base a quella. Se per caso&#8230;<br \/>\n4) &#8230;si \u00e8 trattato di una sovrastima, verr\u00e0 &#8220;compensata&#8221; nel rendiconto successivo, scalando dal venduto effettivo. Quindi alla fine i dati saranno giusti ma&#8230;<br \/>\n5) &#8230;da un anno all&#8217;altro pu\u00f2 prodursi l&#8217;impressione (fallace) di una brusca contrazione nel venduto.<br \/>\nInsomma, l&#8217;Operazione Glasnost non poteva continuare a basarsi sulle cifre indicate nei rendiconti.<br \/>\nL&#8217;anno scorso, almeno per quanto riguarda i titoli usciti con Einaudi, abbiamo fatto un passo in avanti&#8230; e un errore di metodo. Ci siamo fatti comunicare il venduto direttamente dal magazzino, ma anzich\u00e9 ricominciare da capo e chiedere il venduto <em>complessivo<\/em> di ciascun libro, abbiamo chiesto soltanto il dato dall&#8217;1 gennaio al 31 dicembre del 2009, poi l&#8217;abbiamo sommato al totale che ci risultava dagli anni precedenti. Insomma, nonostante le migliori intenzioni, abbiamo fatto un pastrocchio. Certo, le cifre erano <em>pi\u00f9 o meno<\/em> giuste, ma se trasparenza dev&#8217;essere, dobbiamo sforzarci di fornire dati <em>precisi<\/em>.<br \/>\nQuest&#8217;anno, dunque, si riparte da zero. Vi comunichiamo il venduto <span style=\"text-decoration: underline;\">complessivo<\/span> di ciascun nostro libro, <strong>dal giorno dell&#8217;uscita in libreria al 31 maggio 2011<\/strong>, come ci arriva dal magazzino.<br \/>\nNoterete che ci sono solo i libri usciti con Einaudi (o ripubblicati da Einaudi dopo una prima edizione con altro editore). Sono i soli dati che abbiamo al momento. Gli altri li comunicheremo in un addendum, e li accompagneremo a un discorso pi\u00f9 specifico. Sappiate comunque che <em>Havana Glam<\/em>, <em>Free Karma Food<\/em> e <em>Grand River<\/em> sono ufficialmente fuori catalogo. Ci siamo ripresi i diritti. Quelli di <em>Havana Glam<\/em> li abbiamo gi\u00e0 rivenduti, gli altri sono in attesa.<br \/>\nBuona consultazione. Un grazie a Marco Rana e Severino Cesari.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p style=\"text-align: center;\"><em>Q<\/em><br \/>\nIn libreria dal marzo 1999<br \/>\n208.338 nelle varie edizioni Einaudi Stile Libero<br \/>\n+ 120.000 dell\u2019edizione one-shot ne \u201cI Miti\u201d<br \/>\n= <strong>328.338<br \/>\n<\/strong>N.B.\u00a0<em>Q<\/em> \u00e8 stato pubblicato in 18 paesi.<br \/>\nIl venduto planetario \u00e8 stimato intorno alle 500.000 copie.<\/p>\n<p style=\"text-align: center;\"><em>Asce di guerra<\/em><br \/>\nIn libreria dal settembre 2000<br \/>\n16910 in edizione Tropea<br \/>\n+ 12629 Einaudi Stile Libero<br \/>\n= <strong>29.539<\/strong><\/p>\n<p style=\"text-align: center;\"><em>54<\/em><br \/>\nIn libreria dal marzo 2002<br \/>\n= <strong>79.430<\/strong><br \/>\n(Einaudi Stile Libero + Einaudi Tascabili)<br \/>\n<em><br \/>\nGiap!<br \/>\n<\/em> In libreria dal marzo 2003)<br \/>\n= <strong>14.476<\/strong><br \/>\n(Einaudi Stile Libero)<\/p>\n<p style=\"text-align: center;\"><em>Guerra agli Umani<br \/>\n<\/em>In libreria dall&#8217;aprile 2004<br \/>\n=<strong> 32.552<\/strong><br \/>\n(Einaudi Stile Libero + Tascabili Einaudi)<\/p>\n<p style=\"text-align: center;\"><em>New Thing<\/em><br \/>\nIn libreria dall&#8217;ottobre 2004)<br \/>\n= <strong>23.097<\/strong><br \/>\n(Einaudi Stile Libero)<\/p>\n<p style=\"text-align: center;\"><em>Manituana<\/em><br \/>\nIn libreria dal marzo 2007<br \/>\n= <strong>62.234<\/strong><br \/>\n(Einaudi Stile Libero + Einaudi Tascabili)<\/p>\n<p style=\"text-align: center;\"><em>Previsioni del Tempo<\/em><br \/>\nIn libreria dal febbraio 2008<br \/>\n5.260\u00a0nelle Edizioni Ambiente<br \/>\n+ 5114 nell&#8217;edizione Einaudi Stile Libero<br \/>\n= <strong>10.374<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Stella del Mattino<\/em><br \/>\nIn libreria dall&#8217;aprile 2008<br \/>\n= <strong>17.990<\/strong><br \/>\nEinaudi Stile Libero<em><br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\"><em> New Italian Epic<\/em><br \/>\nIn libreria dal maggio 2009<br \/>\n= <strong>4.892<\/strong><br \/>\n(Einaudi Stile Libero)<\/p>\n<p style=\"text-align: center;\"><em>Altai<\/em><br \/>\nIn libreria dall&#8217;ottobre 2009<br \/>\n= <strong>65.392<\/strong><br \/>\n(Einaudi Stile Libero)<\/p>\n<p style=\"text-align: center;\"><em>Anatra all&#8217;arancia meccanica<\/em><br \/>\nIn libreria dal febbraio 2011<br \/>\n= <strong>12.785<\/strong><br \/>\n(Einaudi Stile Libero)<\/p>\n","protected":false},"excerpt":{"rendered":"Come ogni anno, ecco l&#8217;Operazione Glasnost. [Per i pi\u00f9 giovani: glasnost significa &#8220;trasparenza&#8221; in russo, era una parola molto in voga ai tempi di Gorbaciov. ]","protected":false},"author":1,"featured_media":4560,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[961,962],"class_list":["post-4550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-e-segnalazioni","tag-glasnost","tag-gorbaciov"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasparenza: il venduto dei nostri libri al 31\/05\/2011 &#8211; Giap<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasparenza: il venduto dei nostri libri al 31\/05\/2011 &#8211; Giap\" \/>\n<meta property=\"og:description\" content=\"Come ogni anno, ecco l&#8217;Operazione Glasnost. [Per i pi\u00f9 giovani: glasnost significa &#8220;trasparenza&#8221; in russo, era una parola molto in voga ai tempi di Gorbaciov. ]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/\" \/>\n<meta property=\"og:site_name\" content=\"Giap\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-22T19:54:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-06-22T20:03:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wu Ming\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:site\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wu Ming\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/\"},\"author\":{\"name\":\"Wu Ming\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"headline\":\"Trasparenza: il venduto dei nostri libri al 31\\\/05\\\/2011\",\"datePublished\":\"2011-06-22T19:54:24+00:00\",\"dateModified\":\"2011-06-22T20:03:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/\"},\"wordCount\":755,\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/gn_02967.jpg\",\"keywords\":[\"Glasnost\",\"Gorbaciov\"],\"articleSection\":[\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/\",\"name\":\"Trasparenza: il venduto dei nostri libri al 31\\\/05\\\/2011 &#8211; Giap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/gn_02967.jpg\",\"datePublished\":\"2011-06-22T19:54:24+00:00\",\"dateModified\":\"2011-06-22T20:03:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/gn_02967.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/gn_02967.jpg\",\"width\":500,\"height\":380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2011\\\/06\\\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasparenza: il venduto dei nostri libri al 31\\\/05\\\/2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\",\"name\":\"Giap\",\"description\":\"Il sito ufficiale di Wu Ming, collettivo di scrittori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\",\"name\":\"Wu Ming\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"caption\":\"Wu Ming\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011 &#8211; Giap","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/","og_locale":"it_IT","og_type":"article","og_title":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011 &#8211; Giap","og_description":"Come ogni anno, ecco l&#8217;Operazione Glasnost. [Per i pi\u00f9 giovani: glasnost significa &#8220;trasparenza&#8221; in russo, era una parola molto in voga ai tempi di Gorbaciov. ]","og_url":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/","og_site_name":"Giap","article_published_time":"2011-06-22T19:54:24+00:00","article_modified_time":"2011-06-22T20:03:36+00:00","og_image":[{"width":500,"height":380,"url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg","type":"image\/jpeg"}],"author":"Wu Ming","twitter_card":"summary_large_image","twitter_creator":"@Wu_Ming_Foundt","twitter_site":"@Wu_Ming_Foundt","twitter_misc":{"Scritto da":"Wu Ming","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#article","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/"},"author":{"name":"Wu Ming","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"headline":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011","datePublished":"2011-06-22T19:54:24+00:00","dateModified":"2011-06-22T20:03:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/"},"wordCount":755,"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg","keywords":["Glasnost","Gorbaciov"],"articleSection":["Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/","url":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/","name":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011 &#8211; Giap","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#primaryimage"},"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg","datePublished":"2011-06-22T19:54:24+00:00","dateModified":"2011-06-22T20:03:36+00:00","author":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"breadcrumb":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#primaryimage","url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg","contentUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2011\/06\/gn_02967.jpg","width":500,"height":380},{"@type":"BreadcrumbList","@id":"https:\/\/www.wumingfoundation.com\/giap\/2011\/06\/trasparenza-il-venduto-dei-nostri-libri-al-31052011\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wumingfoundation.com\/giap\/"},{"@type":"ListItem","position":2,"name":"Trasparenza: il venduto dei nostri libri al 31\/05\/2011"}]},{"@type":"WebSite","@id":"https:\/\/www.wumingfoundation.com\/giap\/#website","url":"https:\/\/www.wumingfoundation.com\/giap\/","name":"Giap","description":"Il sito ufficiale di Wu Ming, collettivo di scrittori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wumingfoundation.com\/giap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f","name":"Wu Ming","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","caption":"Wu Ming"}}]}},"_links":{"self":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/4550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/comments?post=4550"}],"version-history":[{"count":0,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/4550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media\/4560"}],"wp:attachment":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media?parent=4550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/categories?post=4550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/tags?post=4550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}