{"id":11822,"date":"2013-02-12T08:00:59","date_gmt":"2013-02-12T07:00:59","guid":{"rendered":"http:\/\/www.wumingfoundation.com\/giap\/?p=11822"},"modified":"2013-02-13T23:30:02","modified_gmt":"2013-02-13T22:30:02","slug":"ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line","status":"publish","type":"post","link":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/","title":{"rendered":"Ecco l&#8217;ebook: \u00abGiap. L&#8217;archivio e la strada\u00bb, da oggi in tutte le librerie on line"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.ultimabooks.it\/giap-l-archivio-e-la-strada\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11823\" title=\"giap_archivio_strada-1\" src=\"http:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg\" alt=\"\" width=\"500\" height=\"666\" \/><\/a><\/p>\n<p>Ecco l&#8217;esperimento che in tanti ci avete chiesto di fare. \u00abS\u00ec, il giorno che licenziano il papa!\u00bb, abbiamo risposto una volta a un lettore, tanto per buttarla in ridere, ma intanto riflettevamo. Sempre pi\u00f9 lettori ci hanno consigliato di esser meno rigidi sulla questione ebook. Morale della favola: per la prima volta da quando esiste Wu Ming, facciamo un passo indietro rispetto a uno dei nostri comandamenti, ovvero: \u00abNon chiederai soldi per il download di un libro digitale\u00bb. Per <a href=\"http:\/\/www.ultimabooks.it\/giap-l-archivio-e-la-strada\">questo qui<\/a> ve li chiediamo: costa quattro euro (vabbe&#8217;, meno un centesimo).<!--more--><\/p>\n<h3><strong>Cio\u00e8 3,99 euri? E perch\u00e9 mai?<\/strong><\/h3>\n<div id=\"attachment_11848\" style=\"width: 234px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11848\" class=\"size-full wp-image-11848\" title=\"Tommaso De Lorenzis\" src=\"http:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/Tommaso.png\" alt=\"Tommaso De Lorenzis\" width=\"224\" height=\"273\" \/><p id=\"caption-attachment-11848\" class=\"wp-caption-text\">Tommaso De Lorenzis<\/p><\/div>\n<p><em><a href=\"http:\/\/www.ultimabooks.it\/giap-l-archivio-e-la-strada\">Giap. L&#8217;archivio e la strada<\/a><\/em> \u00e8 in Creative Commons e senza DRM. Con ogni probabilit\u00e0, gi\u00e0 un minuto dopo il primo acquisto lo troverete gratis in molti luoghi della rete.<br \/>\nInoltre, il libro \u00e8 una raccolta di post apparsi su <em>Giap <\/em>nei primi tre anni di esistenza del blog. Gli unici testi davvero inediti sono l&#8217;introduzione e le premesse tematiche di <strong>Tommaso De Lorenzis<\/strong>, l&#8217;antologizzatore <em>par excellence<\/em>.<br \/>\nVa detto che per riproporli in ebook abbiamo fatto un grosso lavoro di editing. Tommaso e\u00a0<strong>Hubertphava<\/strong> &#8211; il nostro mago dei formati digitali &#8211;\u00a0ci hanno lavorato per qualche mese, abbiamo selezionato i post e li abbiamo divisi per sezioni tematiche, c&#8217;\u00e8 un saggio introduttivo di Tommaso pi\u00f9 una breve premessa per ogni sezione&#8230; Insomma, non \u00e8 stato un semplice \u00abtravaso\u00bb di testi. Grossomodo, per\u00f2, sono post apparsi su <em>Giap\u00a0<\/em>che\u00a0molti di voi hanno gi\u00e0 letto (o ascoltato, perch\u00e9 abbiamo anche trascritto l&#8217;audio di alcune conferenze: <em>Patria e morte<\/em>, <em>Tripoli suol del dolore<\/em> e <em>L&#8217;occhio del purgatorio<\/em>).\u00a0Se aggiungiamo che quasi tutti erano gi\u00e0 salvabili in formato ePub e continueranno a esserlo,\u00a0avete tutto il diritto di porre la domanda: perch\u00e9 dovremmo pagare quattro euri per scaricare &#8216;sto libro? Che ci abbiamo scritto in fronte, \u00abgiocondo\u00bb? Non \u00e8 che ci avete presi per deficienti?<\/p>\n<h3><strong>\u00abVe state a suicida&#8217;!<\/strong>\u00bb<strong>\u00a0<\/strong><\/h3>\n<p><a href=\"http:\/\/www.wumingfoundation.com\/giap\/?p=8742\">L&#8217;estate scorsa, col cuore in mano<\/a>\u00a0e l&#8217;altra mano sulle palle, abbiamo spiegato che, per tanti motivi, si \u00e8 esaurito il circolo virtuoso tra i download gratuiti dei nostri libri e l&#8217;acquisto delle versioni cartacee. Una volta pi\u00f9 si scaricava e pi\u00f9 vendevamo, ma quell&#8217;epoca \u00e8 finita, quell&#8217;opzione \u00e8 sconfitta. Se oggi mettiamo i libri scaricabili gratis \u00e8 solo perch\u00e9 lo riteniamo eticamente e politicamente giusto, \u00e8 militanza per la libera circolazione della cultura, che magari fa bene alla reputazione, ma sui nostri redditi ha ricadute scarse. L&#8217;editoria tradizionale, poi, definirla \u00abmalconcia\u00bb\u00a0non rende l&#8217;idea.\u00a0Le donazioni via PayPal o via Flattr sono dimostrazioni di stima che ci commuovono, ma pochi lettori scelgono di farle. Mettiamoci anche il carico da undici, cio\u00e8 che siamo in quattro e con le royalties \u00e8\u00a0\u00abstecca para per tutti\u00bb. Insomma, non butta mica tanto bene.<br \/>\nNel corso della discussione appena linkata, svariati giapster ci dissero, in soldoni:<\/p>\n<blockquote><p>\u00abSu, non siate iper-ideologici&#8230; Fatelo, un esperimento con un ebook a pagamento&#8230; Ne fate tanti di esperimenti, che vi costa fare anche questo? Se la cifra \u00e8 ragionevole, io lo compro&#8230; Che ci guadagnate a essere cos\u00ec talebani? Guardate che se continuate cos\u00ec vi suicidate&#8230;\u00bb<\/p><\/blockquote>\n<p>e altre cose amene che fa sempre piacere sentirsi dire.<\/p>\n<h3>\u00ab<strong>Dirotta su Simplicissimus!<\/strong>\u00bb<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-11844\" title=\"Simplicissimus Book Farm\" src=\"http:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/logo_simplicissimus-300x300.jpg\" alt=\"Simplicissimus Book Farm\" width=\"250\" height=\"250\" \/>Coincidenza volle che tra i vari progetti in cantiere ci fosse anche quello di un&#8217;antologia di <em>Giap<\/em>. Ne avevamo gi\u00e0 fatta una, sempre con Tommaso, esattamente dieci anni fa, quando <em>Giap<\/em> era ancora una newsletter spedita via email. L&#8217;idea era di chiudere un trittico: dopo <em>Giap. Tre anni di narrazioni e movimenti<\/em> (2003) e i racconti di\u00a0<em>Anatra all&#8217;arancia meccanica<\/em> (2011), Tommaso non si era ancora cimentato coi testi e le discussioni di questo blog. Quell&#8217;idea, per\u00f2, non sapevamo a quale editore proporla, e soprattutto dove infilarla nel calendario del 2013, visto che ad aprile uscir\u00e0 <em>Point Lenana<\/em> della coppia WM1\/Santachiara e in autunno <em>L&#8217;armata dei sonnambuli<\/em> del collettivo WM al completo. Due progetti vasti e ambiziosi (e chiss\u00e0 se riusciremo ancora ad avviarne di quella portata) che avrebbero soffocato l&#8217;eventuale antologia. A meno che&#8230;<br \/>\nA meno che l&#8217;antologia non uscisse <em>in un altro posto e in un altro modo<\/em>. Poteva essere l&#8217;occasione giusta per fare il famoso esperimento.<br \/>\nAbbiamo contattato <a href=\"http:\/\/it.wikipedia.org\/wiki\/Simplicissimus_Book_Farm\">Simplicissimus Book Farm<\/a>\u00a0e fatto la proposta. L&#8217;hanno accettata con entusiasmo, e ci si \u00e8 messi tutti al lavoro. S\u00ec, lavoro. Gi\u00e0 scriverli, &#8216;sti post, aveva richiesto studi e ore rubate al sonno. Gi\u00e0 portare avanti le discussioni aveva richiesto culo quadro e mazzo tanto. Aggiungiamoci lo sbattimento <em>specifico<\/em>, cio\u00e8 quello occorso per <em>fare<\/em> l&#8217;ebook, e capirete che non vi stiamo proponendo qualcosa di \u00abtirato via\u00bb, ma un testo sensato, fortemente voluto e curato.<\/p>\n<h3>La \u00abquarta di copertina\u00bb<\/h3>\n<p><em>Giap<\/em> \u00e8 il blog del collettivo di scrittori Wu Ming, autori di <em>Q<\/em>, <em>54<\/em> e svariati altri libri, collettivi e \u00absolisti\u00bb. Ma non \u00e8 solo un blog: \u00e8 il crocevia di una libera comunit\u00e0 di scrittori, lettori e cantastorie. <em>Giap<\/em> d\u00e0 voce a un ragionamento corale intorno all\u2019arte del narrare, alla cultura di massa, ai comportamenti sociali, alle pratiche dell\u2019agire politico, agli effetti dell\u2019innovazione tecnologica.<br \/>\n<em>Giap. L&#8217;archivio e la strada<\/em> raccoglie i pi\u00f9 significativi post pubblicati da Wu Ming tra il 2010 e il 2012. Divisi in sezioni tematiche, i materiali del libro\u00a0raccontano il passaggio tra due decadi, compongono le cronache dell\u2019et\u00e0 del grande crack e del crash della democrazia, dell\u2019<em>austerity<\/em> e della guerra al debito, mentre sull\u2019altra sponda del Mediterraneo il vento sta girando. Tra saggi informali, appunti diseguali e note sparse, echi del passato e visioni del futuro, cinema e tv, letteratura e storia, si snoda una riflessione sullo statuto delle narrazioni, il lavoro culturale nell\u2019epoca del touch screen, il \u00abChe fare?\u00bb nella stagione dei social network, la natura della tecnica, l\u2019ipnotico potere degli orologi e gli imprevisti granelli di sabbia che possono ancora incepparne i congegni. Di pagina in pagina, nelle pieghe di un\u2019indagine che disseziona questo tempo, s\u2019incontrano familisti amorali, sadici italiani e minatori cileni sepolti vivi, il dottor Balanzone e il bombarolo Guy Fawkes, Pier Paolo Pasolini e Ugo Tognazzi, Michel Foucault e Vladimir Majakovskij, Henry Jenkins e Roberto Benigni, carbonari, colonialisti, fotografi visionari, pittori allucinati, rivoltosi e rivoluzionari.<br \/>\nNon un semplice <em>greatest hits<\/em>, ma la verifica collettiva d\u2019un sapere pratico e trasformativo all\u2019incrocio tra pixel, \u00abC\u2019era una volta\u00bb e selciato della via.<\/p>\n<p><strong>Tommaso De Lorenzis<\/strong>\u00a0ha curato le antologie di Wu Ming\u00a0<em>Giap! Tre anni di narrazioni e movimenti<\/em>\u00a0(Einaudi 2003) e<em>\u00a0Anatra all&#8217;arancia meccanica\u00a0<\/em>(Einaudi 2011). Con Mauro Favale \u00e8 autore del libro\u00a0<em>L&#8217;aspra stagione\u00a0<\/em>(Einaudi 2012). E&#8217; uno dei fondatori e animatori dell&#8217;agenzia letteraria Vicolo Cannery.<\/p>\n<p><strong>Wu Ming <\/strong>\u00e8 l&#8217;opificio di scrittori che ha manufatto i romanzi <em>Q<\/em>, <em>54<\/em>, <em>Manituana<\/em>, <em>Altai<\/em> e svariati altri.<\/p>\n<h3>Giap. L&#8217;archivio e la strada<\/h3>\n<p>E cos\u00ec, da oggi parte quest&#8217;esperimento, facciamo il tanto reclamato \u00abpasso indietro\u00bb, ma &#8211; attenzione! &#8211; senza nulla togliere alla nostra policy di libera circolazione. Come si diceva, \u00e8 in Creative Commons e non c&#8217;\u00e8 DRM. E allora torniamo al punto di partenza, con il lettore che domanda: perch\u00e9 dovrei pagarlo quattro euri?<\/p>\n<blockquote><p><em>\u00abE io che cosa posso rispondergli? Posso dirgli, guarda, Tacconi, lass\u00f9 mi hanno ridotto che a fatica mi difendo, lass\u00f9 se caschi per terra nessuno ti raccatta,\u00a0e la forza che ho mi basta appena\u00a0per non farmi mangiare dalle formiche, e se riesco a campare, credi pure che la vita \u00e8 agra, lass\u00f9.\u00bb<\/em>\u00a0(Luciano Bianciardi,<em>\u00a0\u00abLa vita agra\u00bb).<\/em><\/p><\/blockquote>\n<p><a href=\"http:\/\/www.ultimabooks.it\/giap-l-archivio-e-la-strada\"><em>Giap. L&#8217;archivio e la strada<\/em>. In tutte le librerie on line<\/a><br \/>\n(o per essere meno vaghi: in tutte <a href=\"http:\/\/blog.sbfstealth.com\/gli-store-collegati-a-stealth\/\">le librerie on line collegate a Stealth<\/a>).<\/p>\n<div id=\"attachment_11891\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11891\" class=\"size-full wp-image-11891\" title=\"Lettori d'eccezione\" src=\"http:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/lettorideccezione.jpg\" alt=\"Lettori d'eccezione\" width=\"500\" height=\"281\" \/><p id=\"caption-attachment-11891\" class=\"wp-caption-text\">C&#39;\u00e8 chi lo ha ricevuto in anteprima.<\/p><\/div>\n<p>Su quest&#8217;esperimento <a href=\"http:\/\/www.huffingtonpost.it\/carmine-saviano\/quattro-chiacchiere-con-i-wu-ming_b_2667328.html\">ci ha intervistati l&#8217;affintonp\u00f2st<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Ecco l&#8217;esperimento che in tanti ci avete chiesto di fare. \u00abS\u00ec, il giorno che licenziano il papa!\u00bb, abbiamo risposto una volta a un lettore, tanto per buttarla in ridere, ma intanto riflettevamo. Sempre pi\u00f9 lettori ci hanno consigliato di esser meno rigidi sulla questione ebook. Morale della favola: per la prima volta da quando esiste [&hellip;]","protected":false},"author":1,"featured_media":11823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1648,4,6],"tags":[1005,1647,961,1649,1650,249],"class_list":["post-11822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ebookgiap","category-recensioni","category-news-e-segnalazioni","tag-ebook","tag-giap-larchivio-e-la-strada","tag-glasnost","tag-simplicissimus","tag-simplicissimus-book-farm","tag-tommaso-de-lorenzis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giap. L&#039;archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook<\/title>\n<meta name=\"description\" content=\"Giap. L&#039;archivio e la strada \u00e8 l&#039;ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giap. L&#039;archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook\" \/>\n<meta property=\"og:description\" content=\"Giap. L&#039;archivio e la strada \u00e8 l&#039;ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/\" \/>\n<meta property=\"og:site_name\" content=\"Giap\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-12T07:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-02-13T22:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wu Ming\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:site\" content=\"@Wu_Ming_Foundt\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wu Ming\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/\"},\"author\":{\"name\":\"Wu Ming\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"headline\":\"Ecco l&#8217;ebook: \u00abGiap. L&#8217;archivio e la strada\u00bb, da oggi in tutte le librerie on line\",\"datePublished\":\"2013-02-12T07:00:59+00:00\",\"dateModified\":\"2013-02-13T22:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/\"},\"wordCount\":1306,\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/giap_archivio_strada-1.jpg\",\"keywords\":[\"ebook\",\"Giap. L'archivio e la strada\",\"Glasnost\",\"Simplicissimus\",\"Simplicissimus Book Farm\",\"Tommaso De Lorenzis\"],\"articleSection\":[\"Giap. L'archivio e la strada\",\"Libri\",\"Notizie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/\",\"name\":\"Giap. L'archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/giap_archivio_strada-1.jpg\",\"datePublished\":\"2013-02-12T07:00:59+00:00\",\"dateModified\":\"2013-02-13T22:30:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\"},\"description\":\"Giap. L'archivio e la strada \u00e8 l'ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/giap_archivio_strada-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/giap_archivio_strada-1.jpg\",\"width\":500,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/2013\\\/02\\\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecco l&#8217;ebook: \u00abGiap. L&#8217;archivio e la strada\u00bb, da oggi in tutte le librerie on line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#website\",\"url\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/\",\"name\":\"Giap\",\"description\":\"Il sito ufficiale di Wu Ming, collettivo di scrittori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wumingfoundation.com\\\/giap\\\/#\\\/schema\\\/person\\\/881b1c925aaf48fe6eb5c3970be4458f\",\"name\":\"Wu Ming\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g\",\"caption\":\"Wu Ming\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giap. L'archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook","description":"Giap. L'archivio e la strada \u00e8 l'ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/","og_locale":"it_IT","og_type":"article","og_title":"Giap. L'archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook","og_description":"Giap. L'archivio e la strada \u00e8 l'ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...","og_url":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/","og_site_name":"Giap","article_published_time":"2013-02-12T07:00:59+00:00","article_modified_time":"2013-02-13T22:30:02+00:00","og_image":[{"width":500,"height":666,"url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg","type":"image\/jpeg"}],"author":"Wu Ming","twitter_card":"summary_large_image","twitter_creator":"@Wu_Ming_Foundt","twitter_site":"@Wu_Ming_Foundt","twitter_misc":{"Scritto da":"Wu Ming","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#article","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/"},"author":{"name":"Wu Ming","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"headline":"Ecco l&#8217;ebook: \u00abGiap. L&#8217;archivio e la strada\u00bb, da oggi in tutte le librerie on line","datePublished":"2013-02-12T07:00:59+00:00","dateModified":"2013-02-13T22:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/"},"wordCount":1306,"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg","keywords":["ebook","Giap. L'archivio e la strada","Glasnost","Simplicissimus","Simplicissimus Book Farm","Tommaso De Lorenzis"],"articleSection":["Giap. L'archivio e la strada","Libri","Notizie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/","url":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/","name":"Giap. L'archivio e la strada. Scritti di Wu Ming 2010 - 2012, ebook","isPartOf":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#primaryimage"},"image":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg","datePublished":"2013-02-12T07:00:59+00:00","dateModified":"2013-02-13T22:30:02+00:00","author":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f"},"description":"Giap. L'archivio e la strada \u00e8 l'ebook che raccoglie, a cura di Tommaso De Lorenzis, i post pi\u00f9 significativi del triennio 2010-2012...","breadcrumb":{"@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#primaryimage","url":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg","contentUrl":"https:\/\/www.wumingfoundation.com\/giap\/wp-content\/uploads\/2013\/02\/giap_archivio_strada-1.jpg","width":500,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.wumingfoundation.com\/giap\/2013\/02\/ecco-lebook-di-giap-larchivio-e-la-strada-in-tutte-le-librerie-on-line\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wumingfoundation.com\/giap\/"},{"@type":"ListItem","position":2,"name":"Ecco l&#8217;ebook: \u00abGiap. L&#8217;archivio e la strada\u00bb, da oggi in tutte le librerie on line"}]},{"@type":"WebSite","@id":"https:\/\/www.wumingfoundation.com\/giap\/#website","url":"https:\/\/www.wumingfoundation.com\/giap\/","name":"Giap","description":"Il sito ufficiale di Wu Ming, collettivo di scrittori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wumingfoundation.com\/giap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.wumingfoundation.com\/giap\/#\/schema\/person\/881b1c925aaf48fe6eb5c3970be4458f","name":"Wu Ming","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f49001124f0d5b3aeb1d387dbd89e7b48de4c5c15539460ec1c154566c1723c?s=96&d=blank&r=g","caption":"Wu Ming"}}]}},"_links":{"self":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/11822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/comments?post=11822"}],"version-history":[{"count":0,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/posts\/11822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media\/11823"}],"wp:attachment":[{"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/media?parent=11822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/categories?post=11822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wumingfoundation.com\/giap\/wp-json\/wp\/v2\/tags?post=11822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}